{"id":27,"count":37,"description":"La collection City eBike de Galaxy Bicycle offre une gamme vari\u00e9e de v\u00e9los \u00e9lectriques con\u00e7us pour les d\u00e9placements urbains et les promenades de loisir. Ces v\u00e9los \u00e9lectriques allient un design moderne \u00e0 des performances fiables, avec des cadres traversants, des syst\u00e8mes de vitesses Shimano \u00e0 7 rapports et de puissantes batteries lithium-ion. Les mod\u00e8les Velopro C300E et C600E sont con\u00e7us pour les trajets quotidiens sur de longues distances, tandis que les mod\u00e8les C250E et C080E sont polyvalents et conviennent aussi bien aux trajets urbains qu'aux aventures tout-terrain. Que vous fassiez vos courses quotidiennes ou que vous exploriez de nouveaux chemins, les City eBikes de Galaxy vous offrent confort, style et efficacit\u00e9.","link":"https:\/\/galaxybicycle.com\/fr\/product-category\/city-ebike\/","name":"City Ebike","slug":"city-ebike","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/galaxybicycle.com\/fr\/wp-json\/wp\/v2\/product_cat\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galaxybicycle.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/galaxybicycle.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/galaxybicycle.com\/fr\/wp-json\/wp\/v2\/product?product_cat=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}